{"id":38038,"date":"2016-11-10T20:56:46","date_gmt":"2016-11-10T18:56:46","guid":{"rendered":"https:\/\/kernbeisser.ch\/verschillende-interpretaties-van-eeuwigheid\/"},"modified":"2023-08-26T13:21:56","modified_gmt":"2023-08-26T11:21:56","slug":"verschillende-interpretaties-van-eeuwigheid","status":"publish","type":"post","link":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/","title":{"rendered":"Verschillende interpretaties van eeuwigheid"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text uncode_shortcode_id=\"219209&#8243;]Als eeuwigheid eindeloosheid betekent, wat betekent dat dan? Hier zijn enkele interpretaties:[\/vc_column_text][uncode_list icon=\"fa fa-question\" icon_color=\"accent\" uncode_shortcode_id=\"182210&#8243; icon_color_type=\"uncode-palette\"]<\/p>\n<ul>\n<li>Eeuwigheid is&#8230; tijd zonder begin en zonder einde<\/li>\n<li>Eeuwigheid is&#8230; tijd, met een begin maar zonder einde<\/li>\n<li>Eeuwigheid is&#8230; een eindeloze opeenvolging van tijdperken, met of zonder een duidelijk begin<\/li>\n<li>Eeuwigheid is&#8230; het tegenovergestelde van tijd, d.w.z. tijdloosheid<\/li>\n<li>Eeuwigheid is&#8230; een andere dimensie<\/li>\n<li>Eeuwigheid is&#8230; een toestand (\"dichtbij God\" of iets anders)<\/li>\n<li>Eeuwigheid is&#8230; de hemel (het \"hiernamaals\").<\/li>\n<\/ul>\n<p>[\/uncode_list][vc_column_text uncode_shortcode_id=\"981587&#8243;]Deze varianten zijn verschillend tot tegenstrijdig. Er kunnen andere interpretaties zijn. Maar welke interpretatie hoort bij de Bijbel? En is de bijbelse betekenis opgenomen in deze lijst? Zo ja, waar lezen we daarover?<\/p>\n<p>We zullen de kwestie van de bijbelse context hieronder bekijken. Ik heb alle varianten die hier genoemd worden eerder gehoord van christenen - in gesprekken, in boeken, in studies over het onderwerp. Het is dus helemaal niet zo dat eeuwigheid een duidelijk fenomeen is waar iedereen het over eens is. Dit is niet het geval. Zelfs tussen verschillende Bijbelvertalingen zijn er grote verschillen in hoe de woorden van de basistalen vertaald moeten worden. Het interpreteert en definieert zonder blikken of blozen wat nooit in de tekst wordt gezegd.<\/p>\n<p>Wanneer eeuwigheid als \"eindeloos\" wordt verdedigd, worden meestal maar drie punten genoemd:<\/p>\n<ol>\n<li>De eeuwigheid van God<\/li>\n<li>Eeuwig leven en<\/li>\n<li>De eeuwige straf.<\/li>\n<\/ol>\n<p>Dit zijn als het ware de kernuitspraken die onderling afhankelijk zijn. Het is een constructie die zijn relevantie probeert te ontlenen aan deze drie punten. Maar het is een door en door <em>krakkemikkig systeem<\/em> dat weinig met de Bijbel te maken heeft.<\/p>\n<p>Hoewel veel vertalingen de woorden \"eeuwig\" en \"eeuwigheid\" hebben, zijn er ook Bijbelvertalingen waarin deze woorden nergens voorkomen - omdat ze in de oorspronkelijke talen niet zo bestaan. Dus met de ene Bijbelvertaling lijken deze dingen bevestigd te worden, maar met een andere vertaling is dit niet mogelijk omdat de woorden helemaal niet voorkomen.<\/p>\n<p>Deze discrepanties zouden je oren moeten spitsen en je moeten uitnodigen om de conceptuele wereld van de Bijbel onder de loep te nemen om te zien hoe je die kunt begrijpen.[\/vc_column_text][vc_column_text uncode_shortcode_id=\"156138&#8243;]<\/p>\n<h4>Verdieping<\/h4>\n<ul>\n<li>Bedenk welke gedachten je zelf associeert met het woord \"eeuwigheid\".<\/li>\n<li>Deel met anderen wat hun begrip van het woord is.<\/li>\n<li>Welke inzichten krijg je? Waar komen deze bevindingen vandaan? Wat ontbreekt er aan begrip?<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div><div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"\" data-post-id=\"38038\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n                <\/a>\r\n    <span class=\"pld-like-count-wrap pld-count-wrap\">0    <\/span>\r\n<\/div><div class=\"pld-dislike-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-dislike-trigger pld-like-dislike-trigger  \" title=\"\" data-post-id=\"38038\" data-trigger-type=\"dislike\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                        <i class=\"fas fa-thumbs-down\"><\/i>\r\n                <\/a>\r\n    <span class=\"pld-dislike-count-wrap pld-count-wrap\">0<\/span>\r\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Spreekt de Bijbel over een eindeloze eeuwigheid?<\/p>\n","protected":false},"author":5,"featured_media":35974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[571,652],"tags":[640],"class_list":["post-38038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bijbelse-termen","category-tijd-en-eeuwigheid","tag-eeuwigheid"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verschillende interpretaties van eeuwigheid &#8226; Kernbeisser<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verschillende interpretaties van eeuwigheid &#8226; Kernbeisser\" \/>\n<meta property=\"og:description\" content=\"Spreekt de Bijbel over een eindeloze eeuwigheid?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/\" \/>\n<meta property=\"og:site_name\" content=\"Kernbeisser\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-10T18:56:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-26T11:21:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kernbeisser.ch\/wordpress\/wp-content\/uploads\/2016\/11\/IMG_8390.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karsten Risseeuw\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/verschillende-interpretaties-van-eeuwigheid\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/verschillende-interpretaties-van-eeuwigheid\\\/\"},\"author\":{\"name\":\"Karsten Risseeuw\",\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/#\\\/schema\\\/person\\\/0b580f13a753f529e71c4dfd4e01aea1\"},\"headline\":\"Verschillende interpretaties van eeuwigheid\",\"datePublished\":\"2016-11-10T18:56:46+00:00\",\"dateModified\":\"2023-08-26T11:21:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/verschillende-interpretaties-van-eeuwigheid\\\/\"},\"wordCount\":434,\"publisher\":{\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/verschillende-interpretaties-van-eeuwigheid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kernbeisser.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/IMG_8390.jpg\",\"keywords\":[\"Eeuwigheid\"],\"articleSection\":[\"Bijbelse termen\",\"Tijd en eeuwigheid\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/verschillende-interpretaties-van-eeuwigheid\\\/\",\"url\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/verschillende-interpretaties-van-eeuwigheid\\\/\",\"name\":\"Verschillende interpretaties van eeuwigheid &#8226; Kernbeisser\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/verschillende-interpretaties-van-eeuwigheid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/verschillende-interpretaties-van-eeuwigheid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kernbeisser.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/IMG_8390.jpg\",\"datePublished\":\"2016-11-10T18:56:46+00:00\",\"dateModified\":\"2023-08-26T11:21:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/verschillende-interpretaties-van-eeuwigheid\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/verschillende-interpretaties-van-eeuwigheid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/verschillende-interpretaties-van-eeuwigheid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kernbeisser.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/IMG_8390.jpg\",\"contentUrl\":\"https:\\\/\\\/kernbeisser.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/IMG_8390.jpg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/verschillende-interpretaties-van-eeuwigheid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/kernbeisser-gedachten-over-de-bijbel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verschillende interpretaties van eeuwigheid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/\",\"name\":\"Kernbeisser\",\"description\":\"Gedanken zur Bibel\",\"publisher\":{\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/#organization\",\"name\":\"Kernbeisser Counceling\",\"url\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kernbeisser.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/kernbeisser-logo-420x100px.png\",\"contentUrl\":\"https:\\\/\\\/kernbeisser.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/kernbeisser-logo-420x100px.png\",\"width\":420,\"height\":100,\"caption\":\"Kernbeisser Counceling\"},\"image\":{\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/bsky.app\\\/profile\\\/kernbeisser.bsky.social\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kernbeisser.ch\\\/nl\\\/#\\\/schema\\\/person\\\/0b580f13a753f529e71c4dfd4e01aea1\",\"name\":\"Karsten Risseeuw\",\"description\":\"Karsten Risseeuw (Jg. 1961) ist Theologe, Autor und Content Creator mit Schwerpunkt Paulus-Theologie. Seine evangelikale Pr\u00e4gung f\u00fchrte zu kritischen Fragen, die 2014 zur Gr\u00fcndung von kernbeisser.ch und sp\u00e4ter zum Start seines YouTube-Kanals f\u00fchrten. In einem jahrelangen Dekonstruktions- und Rekonstruktionsprozess entwickelte er eine theologische Position, die akademische Tiefe mit pers\u00f6nlicher Zug\u00e4nglichkeit verbindet. Risseeuw bewegt sich bewusst auf der Grenze zwischen evangelikaler Tradition und progressivem Christentum. Seine Arbeit richtet sich an fragende Evangelikale sowie Menschen, die in Dekonstruktionsprozessen stecken und intellektuelle Tiefe suchen, ohne ihren Glauben zu verlieren. Sein Ansatz: Weg vom religi\u00f6sen Leistungsdenken, hin zur paulinischen Botschaft der Gnade. Mit Hunderten Artikeln und einem mehrsprachigen Online-Angebot (Deutsch, Englisch, Niederl\u00e4ndisch) begleitet er Menschen durch theologische Umbr\u00fcche \u2013 europ\u00e4isch-sachlich, akademisch fundiert, aber nie elit\u00e4r. Es geht ihm nicht prim\u00e4r darum, \u00abwas\u00bb Menschen glauben, sondern \u00abwie\u00bb und \u00abwozu\u00bb sie glauben, damit Lebens- und Glaubensentfaltung stattfinden k\u00f6nnen.\",\"sameAs\":[\"http:\\\/\\\/kernbeisser.ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verschillende interpretaties van eeuwigheid &#8226; Kernbeisser","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/","og_locale":"nl_NL","og_type":"article","og_title":"Verschillende interpretaties van eeuwigheid &#8226; Kernbeisser","og_description":"Spreekt de Bijbel over een eindeloze eeuwigheid?","og_url":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/","og_site_name":"Kernbeisser","article_published_time":"2016-11-10T18:56:46+00:00","article_modified_time":"2023-08-26T11:21:56+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/kernbeisser.ch\/wordpress\/wp-content\/uploads\/2016\/11\/IMG_8390.jpg","type":"image\/jpeg"}],"author":"Karsten Risseeuw","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/#article","isPartOf":{"@id":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/"},"author":{"name":"Karsten Risseeuw","@id":"https:\/\/kernbeisser.ch\/nl\/#\/schema\/person\/0b580f13a753f529e71c4dfd4e01aea1"},"headline":"Verschillende interpretaties van eeuwigheid","datePublished":"2016-11-10T18:56:46+00:00","dateModified":"2023-08-26T11:21:56+00:00","mainEntityOfPage":{"@id":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/"},"wordCount":434,"publisher":{"@id":"https:\/\/kernbeisser.ch\/nl\/#organization"},"image":{"@id":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/#primaryimage"},"thumbnailUrl":"https:\/\/kernbeisser.ch\/wordpress\/wp-content\/uploads\/2016\/11\/IMG_8390.jpg","keywords":["Eeuwigheid"],"articleSection":["Bijbelse termen","Tijd en eeuwigheid"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/","url":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/","name":"Verschillende interpretaties van eeuwigheid &#8226; Kernbeisser","isPartOf":{"@id":"https:\/\/kernbeisser.ch\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/#primaryimage"},"image":{"@id":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/#primaryimage"},"thumbnailUrl":"https:\/\/kernbeisser.ch\/wordpress\/wp-content\/uploads\/2016\/11\/IMG_8390.jpg","datePublished":"2016-11-10T18:56:46+00:00","dateModified":"2023-08-26T11:21:56+00:00","breadcrumb":{"@id":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/#primaryimage","url":"https:\/\/kernbeisser.ch\/wordpress\/wp-content\/uploads\/2016\/11\/IMG_8390.jpg","contentUrl":"https:\/\/kernbeisser.ch\/wordpress\/wp-content\/uploads\/2016\/11\/IMG_8390.jpg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/kernbeisser.ch\/nl\/verschillende-interpretaties-van-eeuwigheid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kernbeisser.ch\/nl\/kernbeisser-gedachten-over-de-bijbel\/"},{"@type":"ListItem","position":2,"name":"Verschillende interpretaties van eeuwigheid"}]},{"@type":"WebSite","@id":"https:\/\/kernbeisser.ch\/nl\/#website","url":"https:\/\/kernbeisser.ch\/nl\/","name":"Kernbeisser","description":"Gedanken zur Bibel","publisher":{"@id":"https:\/\/kernbeisser.ch\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kernbeisser.ch\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/kernbeisser.ch\/nl\/#organization","name":"Kernbeisser Counceling","url":"https:\/\/kernbeisser.ch\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/kernbeisser.ch\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/kernbeisser.ch\/wordpress\/wp-content\/uploads\/kernbeisser-logo-420x100px.png","contentUrl":"https:\/\/kernbeisser.ch\/wordpress\/wp-content\/uploads\/kernbeisser-logo-420x100px.png","width":420,"height":100,"caption":"Kernbeisser Counceling"},"image":{"@id":"https:\/\/kernbeisser.ch\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/bsky.app\/profile\/kernbeisser.bsky.social"]},{"@type":"Person","@id":"https:\/\/kernbeisser.ch\/nl\/#\/schema\/person\/0b580f13a753f529e71c4dfd4e01aea1","name":"Karsten Risseeuw","description":"Karsten Risseeuw (Jg. 1961) ist Theologe, Autor und Content Creator mit Schwerpunkt Paulus-Theologie. Seine evangelikale Pr\u00e4gung f\u00fchrte zu kritischen Fragen, die 2014 zur Gr\u00fcndung von kernbeisser.ch und sp\u00e4ter zum Start seines YouTube-Kanals f\u00fchrten. In einem jahrelangen Dekonstruktions- und Rekonstruktionsprozess entwickelte er eine theologische Position, die akademische Tiefe mit pers\u00f6nlicher Zug\u00e4nglichkeit verbindet. Risseeuw bewegt sich bewusst auf der Grenze zwischen evangelikaler Tradition und progressivem Christentum. Seine Arbeit richtet sich an fragende Evangelikale sowie Menschen, die in Dekonstruktionsprozessen stecken und intellektuelle Tiefe suchen, ohne ihren Glauben zu verlieren. Sein Ansatz: Weg vom religi\u00f6sen Leistungsdenken, hin zur paulinischen Botschaft der Gnade. Mit Hunderten Artikeln und einem mehrsprachigen Online-Angebot (Deutsch, Englisch, Niederl\u00e4ndisch) begleitet er Menschen durch theologische Umbr\u00fcche \u2013 europ\u00e4isch-sachlich, akademisch fundiert, aber nie elit\u00e4r. Es geht ihm nicht prim\u00e4r darum, \u00abwas\u00bb Menschen glauben, sondern \u00abwie\u00bb und \u00abwozu\u00bb sie glauben, damit Lebens- und Glaubensentfaltung stattfinden k\u00f6nnen.","sameAs":["http:\/\/kernbeisser.ch"]}]}},"_links":{"self":[{"href":"https:\/\/kernbeisser.ch\/nl\/wp-json\/wp\/v2\/posts\/38038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kernbeisser.ch\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kernbeisser.ch\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kernbeisser.ch\/nl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/kernbeisser.ch\/nl\/wp-json\/wp\/v2\/comments?post=38038"}],"version-history":[{"count":0,"href":"https:\/\/kernbeisser.ch\/nl\/wp-json\/wp\/v2\/posts\/38038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kernbeisser.ch\/nl\/wp-json\/wp\/v2\/media\/35974"}],"wp:attachment":[{"href":"https:\/\/kernbeisser.ch\/nl\/wp-json\/wp\/v2\/media?parent=38038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kernbeisser.ch\/nl\/wp-json\/wp\/v2\/categories?post=38038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kernbeisser.ch\/nl\/wp-json\/wp\/v2\/tags?post=38038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}